{"id":887,"date":"2021-11-30T23:48:06","date_gmt":"2021-11-30T21:48:06","guid":{"rendered":"https:\/\/www.adgt.it\/wordpress\/?page_id=887"},"modified":"2021-11-30T23:48:07","modified_gmt":"2021-11-30T21:48:07","slug":"cavalese-2021-giugno","status":"publish","type":"page","link":"https:\/\/www.adgt.it\/wordpress\/attivita\/2021-attivita\/cavalese-2021-giugno\/","title":{"rendered":"Cavalese 2021 giugno"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Campo ragazzi<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"385\" height=\"326\" src=\"https:\/\/www.adgt.it\/wordpress\/wp-content\/uploads\/2021\/11\/FotoCavalese202106.png\" alt=\"\" class=\"wp-image-888\" srcset=\"https:\/\/www.adgt.it\/wordpress\/wp-content\/uploads\/2021\/11\/FotoCavalese202106.png 385w, https:\/\/www.adgt.it\/wordpress\/wp-content\/uploads\/2021\/11\/FotoCavalese202106-300x254.png 300w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Varie attivit\u00e0 permettono, ai nostri ragazzi, di imparare a gestire il diabete in ogni occasione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E verso il tardo pomeriggio, gli incontri con i nostri esperti: dietista ed educatore, permettono di riflettere sul comportamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La bici di Giorgio Cesari con la borsa che contiene il necessaire per la nostra sicurezza e poi tutti i suoi sogni, i desideri, la visione dell&#8217;esserci sempre per gli altri. Giorgio, presidente dell&#8217;Associazione Diabete Giovanile del Trentino, medico dalla vasta umanit\u00e0, padre di un ragazzo con diabete ora babbo di una bellissima bambina, colonna, insieme ad altre amiche e amici, di AGD Italia.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le bici delle nostre ragazze e dei nostri ragazzi. Oggi abbiamo percorso felici la val di Fassa e la val di Fiemme lungo l&#8217;Avisio.<br>Sotto montagne straordinarie, dentro borghi colorati di fiori, con tutte le loro bellissime vite davanti agli occhi, di progetti colmi i cuori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cosa porti a casa da queste giornate?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>&#8220;Tante emozionanti esperienze, tanti nuovi amici che spero, nei prossimi campi scuola o in altre circostanze, di incontrare ancora e soprattutto una maggiore consapevolezza della responsabilit\u00e0 che il diabete e la sua corretta gestione portano con s\u00e9&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Sta per finire questa intensa settimana di campo scuola con l&#8217;Associazione Diabete Giovanile del Trentino. E&#8217; difficile separarsi ma necessario, per ritrovarsi ancora, colmi di esperienze e parole nuove. Ringrazio sempre la mia storia felice che mi conduce nel cuore del miracolo, dove la vita accade e i cuori si aprono. Dove, senza paure e muri, \u00e8 possibile essere.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campo ragazzi Varie attivit\u00e0 permettono, ai nostri ragazzi, di imparare a gestire il diabete in ogni occasione. E verso il tardo pomeriggio, gli incontri con i nostri esperti: dietista ed educatore, permettono di riflettere sul comportamento. La bici di Giorgio Cesari con la borsa che contiene il necessaire per la nostra sicurezza e poi tutti<\/p>\n<p><a href=\"https:\/\/www.adgt.it\/wordpress\/attivita\/2021-attivita\/cavalese-2021-giugno\/\" class=\"more-link\">Leggi tutto<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":870,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-887","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/pages\/887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/comments?post=887"}],"version-history":[{"count":1,"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/pages\/887\/revisions"}],"predecessor-version":[{"id":889,"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/pages\/887\/revisions\/889"}],"up":[{"embeddable":true,"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/pages\/870"}],"wp:attachment":[{"href":"https:\/\/www.adgt.it\/wordpress\/wp-json\/wp\/v2\/media?parent=887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}